{"id":4349,"date":"2017-04-25T11:49:06","date_gmt":"2017-04-25T09:49:06","guid":{"rendered":"https:\/\/rubencabeza.com\/2013\/04\/25\/la-vida-no-se-estudia-se-vive\/"},"modified":"2020-05-21T23:30:16","modified_gmt":"2020-05-21T21:30:16","slug":"la-vida-no-se-estudia-se-vive","status":"publish","type":"post","link":"https:\/\/rubencabeza.com\/en\/la-vida-no-se-estudia-se-vive\/","title":{"rendered":"LA VIDA NO SE ESTUDIA, SE VIVE"},"content":{"rendered":"<figure class=\"tmblr-full\" data-orig-height=\"205\" data-orig-width=\"500\"><\/figure>\n<p>(Pel\u00edcula El indomable Will Hunting)<\/p>\n<p>\u201cSi te pregunto de arte me responder\u00e1s con datos de todos los libros que se han escrito. Miguel \u00c1ngel: lo sabes todo. Vida y obra, aspiraciones pol\u00edticas, su amistad con el Papa, su orientaci\u00f3n sexual\u2026 Lo que haga falta. Pero t\u00fa no puedes decirme a qu\u00e9 huele la Capilla Sixtina. Nunca has estado all\u00ed y has contemplado ese hermoso techo. No lo has visto.\u201d<!-- more --><\/p>\n<p>Estas son algunas de las cosas que le dice el psic\u00f3logo Sean Maguire (interpretado por Robin Williams) al joven engre\u00eddo y genio de las matem\u00e1ticas Will Hunting (Matt Damon).<\/p>\n<p>Todo esto nos recuerda que la vida es para eso, para vivirla. Leer y conocer est\u00e1 fenomenal, pero es mucho m\u00e1s enriquecedor si experimentamos todo eso. Es muy com\u00fan estar acomodados en\u00a0<em>nuestras teor\u00edas<\/em>\u00a0sentados en el sof\u00e1, creyendo que por haber le\u00eddo mucho sobre algo nos podemos considerar unos<em>\u201centendidos en la materia\u201d<\/em>\u00a0y que nuestra opini\u00f3n vale m\u00e1s que la de otro\u2026 \u00bfY nuestra experiencia sobre ello? \u00bfCu\u00e1ntas veces opinamos, defendemos y hasta ofendemos s\u00f3lo por una idea que nunca hemos vivido?<\/p>\n<p>Vivamos, disfrutemos, pongamos en pr\u00e1ctica las cosas, riamos, lloremos\u2026 y despu\u00e9s compartamos eso con los dem\u00e1s, aportando lo que nosotros hemos descubierto. Ese es nuestro granito de arena. No es el \u00fanico, ni el m\u00e1s importante, ni la verdad absoluta, pero\u2026 es\u00a0<strong><em>el nuestro<\/em><\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Pel\u00edcula El indomable Will Hunting) \u201cSi te pregunto de arte me responder\u00e1s con datos de todos los libros que se han escrito. Miguel \u00c1ngel: lo sabes todo. Vida y obra, aspiraciones pol\u00edticas, su amistad con el Papa, su orientaci\u00f3n sexual\u2026 Lo que haga falta. Pero t\u00fa no puedes decirme a qu\u00e9 huele la Capilla Sixtina. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4906,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[201,135,37,44,32],"_links":{"self":[{"href":"https:\/\/rubencabeza.com\/en\/wp-json\/wp\/v2\/posts\/4349"}],"collection":[{"href":"https:\/\/rubencabeza.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rubencabeza.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rubencabeza.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rubencabeza.com\/en\/wp-json\/wp\/v2\/comments?post=4349"}],"version-history":[{"count":1,"href":"https:\/\/rubencabeza.com\/en\/wp-json\/wp\/v2\/posts\/4349\/revisions"}],"predecessor-version":[{"id":4907,"href":"https:\/\/rubencabeza.com\/en\/wp-json\/wp\/v2\/posts\/4349\/revisions\/4907"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rubencabeza.com\/en\/wp-json\/wp\/v2\/media\/4906"}],"wp:attachment":[{"href":"https:\/\/rubencabeza.com\/en\/wp-json\/wp\/v2\/media?parent=4349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rubencabeza.com\/en\/wp-json\/wp\/v2\/categories?post=4349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rubencabeza.com\/en\/wp-json\/wp\/v2\/tags?post=4349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}