{"id":4292,"date":"2017-04-10T09:39:00","date_gmt":"2017-04-10T07:39:00","guid":{"rendered":"https:\/\/rubencabeza.com\/2013\/12\/04\/la-familia-es-como-un-equipo-entender-los-roles\/"},"modified":"2020-05-22T23:13:22","modified_gmt":"2020-05-22T21:13:22","slug":"la-familia-es-como-un-equipo-entender-los-roles","status":"publish","type":"post","link":"https:\/\/rubencabeza.com\/en\/la-familia-es-como-un-equipo-entender-los-roles\/","title":{"rendered":"LA FAMILIA ES COMO UN EQUIPO. ENTENDER LOS ROLES FAMILIARES."},"content":{"rendered":"<p>Podemos estar acostumbrados a ver y creer que cada uno de los miembros de una familia (padres e hijos) es un ser individual y que no existe una interdependencia entre ellos; que s\u00f3lo en algunas ocasiones lo que le pasa a uno le afecta al otro. Pero realmente la familia es como un equipo. Cada uno desempe\u00f1a su rol, sea o no consciente de cu\u00e1l es. Para que las relaciones entre los miembros de la familia sean fluidas es necesario tener en cuenta varias cuestiones.<!-- more --><\/p>\n<p>Cada uno de nosotros somos un ser humano que ha nacido con una herencia f\u00edsica, pero tambi\u00e9n con una herencia emocional que son \u00fanicas en el mundo. Al igual que el color de nuestros ojos o la estatura, viene dada por la combinaci\u00f3n de los genes que se han ido transmitiendo nuestros ancestros a lo largo de generaciones, tambi\u00e9n nacemos con una \u201cbase\u201d emocional y mental sobre la que se van a ir asentando las vivencias desde el desarrollo intrauterino hasta el momento actual.<\/p>\n<p>A partir de nuestro nacimiento comenzamos a tomar referencias de nuestro entorno, especialmente de nuestros padres (porque ellos son los medios gracias a los cuales nosotros podemos continuar con nuestro desarrollo y aprendizaje) , y tambi\u00e9n del resto de las personas y vivencias con las que tenemos contacto. Esto tiene la funci\u00f3n de ir conociendo c\u00f3mo funciona este mundo y de qu\u00e9 manera uno puede interactuar con todo lo que hay en \u00e9l.<\/p>\n<figure class=\"tmblr-full\" data-orig-height=\"336\" data-orig-width=\"500\"><img decoding=\"async\" src=\"https:\/\/66.media.tumblr.com\/bcd12e2d985582f0a9101457f2d02324\/6e70a73b12fef561-b3\/s540x810\/c66728aa69b84aff63dd1035060ccb482f176515.jpg\" alt=\"image\" data-orig-height=\"336\" data-orig-width=\"500\" \/><\/figure>\n<p>Nuestra adaptaci\u00f3n a los cambios en la vida, teniendo en cuenta lo que necesitamos en cada momento, marcar\u00e1 el camino que tomamos al vivir y c\u00f3mo lo experimentamos.<\/p>\n<p>Una relaci\u00f3n sana y fluida se establece cuando ambas partes se tienen en cuenta y llegan a acuerdos. Esto sucede cuando existe un respeto por la postura o visi\u00f3n de la persona con la que nos estamos relacionando y se ha dejado a un lado el \u00e1nimo de convencer \u201cal de en frente\u201d de que es \u00e9l quien est\u00e1 equivocado. Si esto no est\u00e1 claro, nunca habr\u00e1 una relaci\u00f3n sana y sin dependencias que ocasionen dolor.<\/p>\n<p>&nbsp;<\/p>\n<figure class=\"tmblr-full\" data-orig-height=\"323\" data-orig-width=\"500\"><img decoding=\"async\" src=\"https:\/\/66.media.tumblr.com\/e03c20a42f89145b982d8ef0d9e42358\/6e70a73b12fef561-1a\/s540x810\/c7253360cae2d06b5a30db4fcdb074ff276096c5.jpg\" alt=\"image\" data-orig-height=\"323\" data-orig-width=\"500\" \/><\/figure>\n<p>&nbsp;<\/p>\n<p><strong>\u00bfY qu\u00e9 tiene que ver todo esto con la familia como equipo? Mucho.<\/strong><\/p>\n<p>Recopilemos. Cada miembro de la familia es un ser \u00fanico, y aunque los hijos puedan compartir algo en com\u00fan con sus padres debido a los genes, no quiere decir que sean como ellos. Ni que deban serlo. Nuestros hijos no son nuestros, no nos pertenecen, no tienen que ser como nosotros digamos. Son seres \u00fanicos.<\/p>\n<p>Cada uno hemos crecido con unos condicionantes que han moldeado nuestra forma de pensar y vivir, y debemos ser muy cuidadosos para estimular a nuestros hijos a experimentar responsablemente en lugar de mostrarles y tratarles de convencer que \u201cnuestra verdad\u201d es \u201cla verdad\u201d (con esta actitud podr\u00edamos cortar las alas a sue\u00f1os que podr\u00edan convertirse en realidad).<\/p>\n<p>Los padres necesitamos ser conscientes de que a trav\u00e9s de nuestro ejemplo es como los hijos van a tomar referencias. Nuestra manera de expresarnos verbal y gestualmente, c\u00f3mo nos relacionamos con nuestra pareja, con ellos y con el resto de las personas, la forma de reaccionar ante las cuestiones que nos presenta la vida y c\u00f3mo perseguimos nuestros sue\u00f1os para hacerlos realidad, son algunos ejemplos a tener en cuenta.<\/p>\n<p>Nuestra funci\u00f3n es ser padres y asumir la responsabilidad que ello conlleva. No podemos pedir a nuestros hijos que hagan y que piensen seg\u00fan un rol que no es el suyo. Es labor nuestra estimular, facilitar y acompa\u00f1ar a nuestros hijos en su desarrollo y crecimiento, para que encuentren lo que a ellos les hace felices\u2026 y hagan su camino.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Podemos estar acostumbrados a ver y creer que cada uno de los miembros de una familia (padres e hijos) es un ser individual y que no existe una interdependencia entre ellos; que s\u00f3lo en algunas ocasiones lo que le pasa a uno le afecta al otro. Pero realmente la familia es como un equipo. Cada [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4816,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[38,25,105,107,109,108,106,37,44,32],"_links":{"self":[{"href":"https:\/\/rubencabeza.com\/en\/wp-json\/wp\/v2\/posts\/4292"}],"collection":[{"href":"https:\/\/rubencabeza.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rubencabeza.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rubencabeza.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rubencabeza.com\/en\/wp-json\/wp\/v2\/comments?post=4292"}],"version-history":[{"count":4,"href":"https:\/\/rubencabeza.com\/en\/wp-json\/wp\/v2\/posts\/4292\/revisions"}],"predecessor-version":[{"id":4981,"href":"https:\/\/rubencabeza.com\/en\/wp-json\/wp\/v2\/posts\/4292\/revisions\/4981"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rubencabeza.com\/en\/wp-json\/wp\/v2\/media\/4816"}],"wp:attachment":[{"href":"https:\/\/rubencabeza.com\/en\/wp-json\/wp\/v2\/media?parent=4292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rubencabeza.com\/en\/wp-json\/wp\/v2\/categories?post=4292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rubencabeza.com\/en\/wp-json\/wp\/v2\/tags?post=4292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}